{"id":1622,"date":"2011-07-13T21:54:49","date_gmt":"2011-07-13T19:54:49","guid":{"rendered":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/dahlie_blass_orange_gelb.jpg"},"modified":"2011-07-13T21:54:49","modified_gmt":"2011-07-13T19:54:49","slug":"dahlie_blass_orange_gelb","status":"inherit","type":"attachment","link":"http:\/\/hintz.bplaced.net\/de\/fotos\/botanik\/dahlien\/attachment\/dahlie_blass_orange_gelb\/","title":{"rendered":"Blassorange"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/hintz.bplaced.net\/images\/2011\/07\/dahlie_blass_orange_gelb.jpg'><img width=\"256\" height=\"200\" src=\"http:\/\/hintz.bplaced.net\/images\/2011\/07\/dahlie_blass_orange_gelb.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Dahlie<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"256","height":"200","hwstring_small":"height='96' width='122'","file":"2011\/07\/dahlie_blass_orange_gelb.jpg","sizes":{"thumbnail":{"file":"dahlie_blass_orange_gelb-140x140.jpg","width":"140","height":"140","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/dahlie_blass_orange_gelb-140x140.jpg"},"full":{"file":"dahlie_blass_orange_gelb.jpg","width":256,"height":200,"mime_type":"image\/jpeg","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/dahlie_blass_orange_gelb.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":87,"source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/dahlie_blass_orange_gelb.jpg","_links":{"self":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media\/1622"}],"collection":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/comments?post=1622"}]}}