{"id":2731,"date":"2011-10-01T01:39:44","date_gmt":"2011-09-30T23:39:44","guid":{"rendered":"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg.jpg"},"modified":"2011-10-01T01:39:44","modified_gmt":"2011-09-30T23:39:44","slug":"here-is-kreuzberg","status":"inherit","type":"attachment","link":"http:\/\/hintz.bplaced.net\/de\/fotos\/graffiti\/berlin\/figuren\/mto\/attachment\/here-is-kreuzberg\/","title":{"rendered":"Here is Kreuzberg"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg.jpg'><img width=\"150\" height=\"300\" src=\"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg-150x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg-150x300.jpg 150w, http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg-311x620.jpg 311w, http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg.jpg 514w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"514","height":"1024","hwstring_small":"height='96' width='48'","file":"2011\/10\/Here-is-Kreuzberg.jpg","sizes":{"thumbnail":{"file":"Here-is-Kreuzberg-140x140.jpg","width":"140","height":"140","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg-140x140.jpg"},"medium":{"file":"Here-is-Kreuzberg-150x300.jpg","width":"150","height":"300","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg-150x300.jpg"},"large":{"file":"Here-is-Kreuzberg-311x620.jpg","width":"311","height":"620","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg-311x620.jpg"},"full":{"file":"Here-is-Kreuzberg.jpg","width":514,"height":1024,"mime_type":"image\/jpeg","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"CYBERSHOT","caption":"","created_timestamp":"1238335398","copyright":"","focal_length":"12.5","iso":"100","shutter_speed":"0.00625","title":"Here is Kreuzberg"}},"post":2726,"source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/10\/Here-is-Kreuzberg.jpg","_links":{"self":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media\/2731"}],"collection":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/comments?post=2731"}]}}