{"id":322,"date":"2011-07-13T21:23:38","date_gmt":"2011-07-13T19:23:38","guid":{"rendered":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus.jpg"},"modified":"2011-07-13T21:23:38","modified_gmt":"2011-07-13T19:23:38","slug":"teuteburgerplatzhaus","status":"inherit","type":"attachment","link":"http:\/\/hintz.bplaced.net\/de\/fotos\/graffiti\/berlin\/schrift\/attachment\/teuteburgerplatzhaus\/","title":{"rendered":"Teuteburger"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus.jpg'><img width=\"300\" height=\"113\" src=\"http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus-300x113.jpg\" class=\"attachment-medium size-medium\" alt=\"Teuteburger Platzhaus\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus-300x113.jpg 300w, http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Teuteburger Platzhaus","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"512","height":"194","hwstring_small":"height='48' width='128'","file":"2011\/07\/teuteburgerplatzhaus.jpg","sizes":{"thumbnail":{"file":"teuteburgerplatzhaus-140x140.jpg","width":"140","height":"140","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus-140x140.jpg"},"medium":{"file":"teuteburgerplatzhaus-300x113.jpg","width":"300","height":"113","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus-300x113.jpg"},"full":{"file":"teuteburgerplatzhaus.jpg","width":512,"height":194,"mime_type":"image\/jpeg","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":195,"source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/07\/teuteburgerplatzhaus.jpg","_links":{"self":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media\/322"}],"collection":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/comments?post=322"}]}}