{"id":146,"date":"2011-07-12T21:29:55","date_gmt":"2011-07-12T19:29:55","guid":{"rendered":"http:\/\/hintz.bplaced.net\/?page_id=146"},"modified":"2011-07-31T22:18:57","modified_gmt":"2011-07-31T20:18:57","slug":"oper","status":"publish","type":"page","link":"http:\/\/hintz.bplaced.net\/de\/fotos\/staedte\/dresden\/oper\/","title":{"rendered":"Oper"},"content":{"rendered":"<p><\/p>\n<h1>Die Semperoper in Dresden bei Nacht<\/h1>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-356\" title=\"Semperoper\" src=\"http:\/\/hintz.bplaced.net\/images\/2011\/07\/Semperoper.jpg\" alt=\"Die Semperoper in Dresden bei Nacht\" width=\"512\" height=\"338\" srcset=\"http:\/\/hintz.bplaced.net\/images\/2011\/07\/Semperoper.jpg 512w, http:\/\/hintz.bplaced.net\/images\/2011\/07\/Semperoper-300x198.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n<p>Die Semperoper wurden in den Jahren 1870-1878 erbaut, 1945 wurde sie durch den zweiten Weltkrieg zerst\u00f6rt und bis 1985 wieder original rekonstruiert.<\/p>\n<p>Dieses und die anderen Bilder aus Dresden beweisen, dass man auch nachts, ohne Stativ, bei klirrender K\u00e4lte und mit schwachen Batterien noch stimmungsvolle Aufnahmen machen kann.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Semperoper in Dresden bei Nacht Die Semperoper wurden in den Jahren 1870-1878 erbaut, 1945 wurde sie durch den zweiten Weltkrieg zerst\u00f6rt und bis 1985 wieder original rekonstruiert. Dieses und die anderen Bilder aus Dresden beweisen, dass man auch nachts, ohne Stativ, bei klirrender K\u00e4lte und mit schwachen Batterien noch stimmungsvolle Aufnahmen machen kann.<\/p>\n","protected":false},"author":1,"featured_media":356,"parent":107,"menu_order":2,"comment_status":"open","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/pages\/146"}],"collection":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/comments?post=146"}],"version-history":[{"count":12,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/pages\/146\/revisions"}],"predecessor-version":[{"id":2286,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/pages\/146\/revisions\/2286"}],"up":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/pages\/107"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media\/356"}],"wp:attachment":[{"href":"http:\/\/hintz.bplaced.net\/de\/wp-json\/wp\/v2\/media?parent=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}