{"id":2598,"date":"2011-09-16T04:08:09","date_gmt":"2011-09-16T02:08:09","guid":{"rendered":"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train.jpg"},"modified":"2011-09-16T04:08:09","modified_gmt":"2011-09-16T02:08:09","slug":"cold-train","status":"inherit","type":"attachment","link":"http:\/\/hintz.bplaced.net\/en\/photos\/graffiti\/berlin\/rose-garden\/attachment\/cold-train\/","title":{"rendered":"Cold-Train"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train.jpg'><img width=\"300\" height=\"300\" src=\"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train-300x300.jpg 300w, http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train-140x140.jpg 140w, http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train-620x618.jpg 620w, http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1024","height":"1022","hwstring_small":"height='96' width='96'","file":"2011\/09\/Cold-Train.jpg","sizes":{"thumbnail":{"file":"Cold-Train-140x140.jpg","width":"140","height":"140","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train-140x140.jpg"},"medium":{"file":"Cold-Train-300x300.jpg","width":"300","height":"300","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train-300x300.jpg"},"large":{"file":"Cold-Train-620x618.jpg","width":"620","height":"618","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train-620x618.jpg"},"full":{"file":"Cold-Train.jpg","width":1024,"height":1022,"mime_type":"image\/jpeg","source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train.jpg"}},"image_meta":{"aperture":"6.3","credit":"","camera":"DMC-GH1","caption":"","created_timestamp":"1280511042","copyright":"","focal_length":"15","iso":"100","shutter_speed":"0.005","title":"Cold-Train"}},"post":2613,"source_url":"http:\/\/hintz.bplaced.net\/images\/2011\/09\/Cold-Train.jpg","_links":{"self":[{"href":"http:\/\/hintz.bplaced.net\/en\/wp-json\/wp\/v2\/media\/2598"}],"collection":[{"href":"http:\/\/hintz.bplaced.net\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/hintz.bplaced.net\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hintz.bplaced.net\/en\/wp-json\/wp\/v2\/comments?post=2598"}]}}